{"id":15536,"date":"2025-12-15T12:14:00","date_gmt":"2025-12-15T12:14:00","guid":{"rendered":"https:\/\/esim.lemmetravel.com\/LEMMETravel-eSIM\/Buy-eSIM\/euconnect-5-gb-30-days-2\/"},"modified":"2026-05-13T19:11:48","modified_gmt":"2026-05-13T19:11:48","slug":"euconnect-5-gb-30-days-2","status":"publish","type":"product","link":"https:\/\/esim.lemmetravel.com\/tl\/LEMMETravel-eSIM\/Buy-eSIM\/euconnect-5-gb-30-days-2\/","title":{"rendered":"EUconnect 5 GB \u2013 30 araw"},"content":{"rendered":"<p>Data-only eSIM.<br \/>\nGumagana sa maraming network sa European Union + UK.<\/p>","protected":false},"excerpt":{"rendered":"<p>Data-only eSIM. Gumagana sa maraming network sa European Union + UK.<\/p>","protected":false},"featured_media":15603,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[685],"product_tag":[2294,2295,2290,2264,2245,2265,2244,2246,2289,2274,2272,2286,2282,2277,2237,2278,2256,2267,2268,2280,2283,2284,2269,2271,2276,2281,2279,2285,2270,2275,2273,2260,2251,2259,2299,2239,2254,2253,2236,2302,2303,2304,2242,2240,2298,2249,2300,2243,2248,2291,2241,2252,2238,2250,2255,2263,2257,2301,2261,2293,2292,2266,2287,2288,2258,2262,2297,2296,2247],"class_list":{"0":"post-15536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-european-union-esim","7":"product_tag-4g-europe-esim","8":"product_tag-5g-europe-esim","9":"product_tag-avoid-roaming-charges-europe","10":"product_tag-backpacking-europe-esim","11":"product_tag-best-europe-esim","12":"product_tag-business-travel-europe-esim","13":"product_tag-buy-europe-esim","14":"product_tag-cheap-europe-esim","15":"product_tag-data-roaming-europe","16":"product_tag-esim-austria","17":"product_tag-esim-belgium","18":"product_tag-esim-bulgaria","19":"product_tag-esim-czech-republic","20":"product_tag-esim-denmark","21":"product_tag-esim-europe","22":"product_tag-esim-finland","23":"product_tag-esim-for-europe-travel","24":"product_tag-esim-france","25":"product_tag-esim-germany","26":"product_tag-esim-greece","27":"product_tag-esim-hungary","28":"product_tag-esim-ireland","29":"product_tag-esim-italy","30":"product_tag-esim-netherlands","31":"product_tag-esim-norway","32":"product_tag-esim-poland","33":"product_tag-esim-portugal","34":"product_tag-esim-romania","35":"product_tag-esim-spain","36":"product_tag-esim-sweden","37":"product_tag-esim-switzerland","38":"product_tag-eu-esim","39":"product_tag-europe-connectivity-esim","40":"product_tag-europe-coverage-esim","41":"product_tag-europe-data-bundle","42":"product_tag-europe-data-esim","43":"product_tag-europe-data-plans","44":"product_tag-europe-digital-sim","45":"product_tag-europe-esim","46":"product_tag-europe-esim-deals","47":"product_tag-europe-esim-offers","48":"product_tag-europe-esim-packages","49":"product_tag-europe-esim-plans","50":"product_tag-europe-internet-esim","51":"product_tag-europe-internet-package","52":"product_tag-europe-mobile-data","53":"product_tag-europe-mobile-plan","54":"product_tag-europe-prepaid-esim","55":"product_tag-europe-roaming-esim","56":"product_tag-europe-sim-alternative","57":"product_tag-europe-sim-card","58":"product_tag-europe-tourist-esim","59":"product_tag-europe-travel-esim","60":"product_tag-europe-travel-internet","61":"product_tag-europe-travel-sim","62":"product_tag-europe-trip-esim","63":"product_tag-europe-wide-esim","64":"product_tag-europe-wireless-data","65":"product_tag-european-union-esim","66":"product_tag-fast-internet-europe-travel","67":"product_tag-global-esim-europe","68":"product_tag-holiday-europe-esim","69":"product_tag-internet-in-europe","70":"product_tag-mobile-internet-europe","71":"product_tag-multi-country-europe-esim","72":"product_tag-schengen-esim","73":"product_tag-stay-connected-europe","74":"product_tag-travel-europe-connectivity","75":"product_tag-unlimited-europe-esim","77":"first","78":"instock","79":"virtual","80":"taxable","81":"purchasable","82":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product\/15536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/comments?post=15536"}],"version-history":[{"count":2,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product\/15536\/revisions"}],"predecessor-version":[{"id":18694,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product\/15536\/revisions\/18694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/media\/15603"}],"wp:attachment":[{"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/media?parent=15536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product_brand?post=15536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product_cat?post=15536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esim.lemmetravel.com\/tl\/wp-json\/wp\/v2\/product_tag?post=15536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}